{"id":383,"date":"2023-08-30T12:37:58","date_gmt":"2023-08-30T12:37:58","guid":{"rendered":"https:\/\/bandidoswitzerland.ch\/?page_id=383"},"modified":"2025-02-24T21:13:57","modified_gmt":"2025-02-24T21:13:57","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/bandidoswitzerland.ch\/fr\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"383\" class=\"elementor elementor-383\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d447e82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d447e82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-82d2744\" data-id=\"82d2744\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f360cf6 elementor-nav-menu__align-start elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"f360cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-f360cf6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-392\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/kontakt\/\" class=\"elementor-item\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-394\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/zahlungsarten\/\" class=\"elementor-item\">Zahlungsarten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2474\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/umtausch-und-ruckgabe\/\" class=\"elementor-item\">\u00c9change et retour<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-391\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/haufig-gestellte-fragen\/\" class=\"elementor-item\">H\u00e4ufig gestellte Fragen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-393\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/unsere-kunden\/\" class=\"elementor-item\">Unsere Kunden<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2473\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/uber-uns\/\" class=\"elementor-item\">\u00c0 propos de nous<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2775\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/kontakt\/impressum\/\" class=\"elementor-item\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2798\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/agb\/\" class=\"elementor-item\">AGB<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-f360cf6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-392\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/kontakt\/\" class=\"elementor-item\" tabindex=\"-1\">Kontakt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-394\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/zahlungsarten\/\" class=\"elementor-item\" tabindex=\"-1\">Zahlungsarten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2474\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/umtausch-und-ruckgabe\/\" class=\"elementor-item\" tabindex=\"-1\">\u00c9change et retour<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-391\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/haufig-gestellte-fragen\/\" class=\"elementor-item\" tabindex=\"-1\">H\u00e4ufig gestellte Fragen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-393\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/unsere-kunden\/\" class=\"elementor-item\" tabindex=\"-1\">Unsere Kunden<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2473\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/uber-uns\/\" class=\"elementor-item\" tabindex=\"-1\">\u00c0 propos de nous<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2775\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/kontakt\/impressum\/\" class=\"elementor-item\" tabindex=\"-1\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2798\"><a href=\"https:\/\/bandidoswitzerland.ch\/fr\/agb\/\" class=\"elementor-item\" tabindex=\"-1\">AGB<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4bd40f0\" data-id=\"4bd40f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcda780 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dcda780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Luzernstrasse+29,+4500+Solothurn,+%D0%A8%D0%B2%D0%B5%D0%B9%D1%86%D0%B0%D1%80%D1%96%D1%8F\/data=!4m2!3m1!1s0x4791d7e35e12eb7f:0xd7c7298e797f569a?sa=X&#038;ved=2ahUKEwi0iL67vv-AAxU-hv0HHQvAB5MQ8gF6BAgPEAA&#038;ved=2ahUKEwi0iL67vv-AAxU-hv0HHQvAB5MQ8gF6BAgSEAI\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Adresse: Luzernstrasse 29, 4500 Solothurn, Schweiz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41791997760\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Telefon: +41 79 199 77 60<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:%20shop.3guys@gmail.com\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">E-Mail: shop.3guys@gmail.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8697593 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"8697593\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-9ac5a4f\" href=\"https:\/\/www.facebook.com\/bandido4500\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-43fa22d\" href=\"https:\/\/www.instagram.com\/bandido_schweiz_official\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad811bb elementor-widget elementor-widget-google_maps\" data-id=\"ad811bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Luzernstrasse%2029%2C%204500%20Solothurn&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Luzernstrasse 29, 4500 Solothurn\"\n\t\t\t\t\taria-label=\"Luzernstrasse 29, 4500 Solothurn\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Adresse: Luzernstrasse 29, 4500 Solothurn, Schweiz Telefon: +41 79 199 77 60 E-Mail: shop.3guys@gmail.com Facebook Instagram<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-383","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/bandidoswitzerland.ch\/fr\/wp-json\/wp\/v2\/pages\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bandidoswitzerland.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bandidoswitzerland.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bandidoswitzerland.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bandidoswitzerland.ch\/fr\/wp-json\/wp\/v2\/comments?post=383"}],"version-history":[{"count":0,"href":"https:\/\/bandidoswitzerland.ch\/fr\/wp-json\/wp\/v2\/pages\/383\/revisions"}],"wp:attachment":[{"href":"https:\/\/bandidoswitzerland.ch\/fr\/wp-json\/wp\/v2\/media?parent=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}